{"id":8098,"date":"2019-11-27T16:20:58","date_gmt":"2019-11-27T19:20:58","guid":{"rendered":"https:\/\/xplastic.com.br\/?p=8098"},"modified":"2020-02-26T14:37:33","modified_gmt":"2020-02-26T17:37:33","slug":"literatura-erotica","status":"publish","type":"post","link":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/","title":{"rendered":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa"},"content":{"rendered":"\n<p>Quando <a href=\"https:\/\/xplastic.com.br\/blog\/xgirl-nittie-nua-em-um-ensaio-sensual-exclusivo-xplastic\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"mandei meu primeiro email para a Xplastic (abre numa nova aba)\">mandei meu primeiro email para a Xplastic<\/a> a fim de preencher a vaga de escritor para este blog, precisei mostrar um pouco de mim, um pouco do que eu escrevia. Acontece que, no auge dos meus vinte e tr\u00eas anos e sem qualquer texto impresso publicado \u2014 a n\u00e3o ser que voc\u00ea conte os livros de contos dos alunos da minha escola, \u00e9 claro \u2014, eu cheguei a ficar com vergonha de dizer que tudo o que eu sabia sobre escrever veio, principalmente, das fanfics.<\/p>\n\n\n\n<p>Existe um submundo de hist\u00f3rias e fic\u00e7\u00e3o de f\u00e3, muito al\u00e9m de hist\u00f3rias divertidas envolvendo pessoas famosas. Quem nunca ouviu falar do clich\u00ea da adolescente que sai de casa para ir ao Starbucks e acaba encontrando seu \u00eddolo no meio do caminho? Um homem mais velho, talvez cantor ou um ator famoso, que tem milh\u00f5es de f\u00e3s iguais a ela e que, \u00f3bvio, se apaixona pela mesma. Esse \u00e9 o exemplo mais famoso dos clich\u00eas em fanfics, e n\u00e3o somente o mais famoso como tamb\u00e9m o mais adorado.&nbsp;<\/p>\n\n\n\n<p>Hist\u00f3rias geralmente escritas por adolescentes mais jovens, com personagens desde pessoas famosas na vida real at\u00e9 mesmo personagens de filmes, livros, s\u00e9ries. O mundo das fanfics \u00e9 t\u00e3o extenso e de combina\u00e7\u00f5es improv\u00e1veis que se eu fosse listar cada uma delas, esse artigo teria bem mais de mil p\u00e1ginas.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/kindle-1024x683.jpg\" alt=\"Menina lendo texto no Kindle - literatura er\u00f3tica\" class=\"wp-image-8099\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/kindle-1024x683.jpg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/kindle-512x341.jpg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/kindle-768x512.jpg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/kindle.jpg 1050w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Imagem: Unsplash <\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Literatura er\u00f3tica e o mundo de  conceitos<\/h2>\n\n\n\n<p>Mas, n\u00e3o apenas sendo mero del\u00edrio adolescente, com as fanfics e o crescimento delas vieram tamb\u00e9m ao mundo conceitos claros de misoginia e ideias antifeministas. O mundo liter\u00e1rio ainda \u00e9 cheio de preconceitos mesquinhos que por pouco n\u00e3o acabam de vez com a motiva\u00e7\u00e3o de muitas escritoras.<\/p>\n\n\n\n<p>Me explico: sabe quando dizem que cozinhar \u00e9 coisa de mulher? Que mulher s\u00f3 serve para ser piloto de fog\u00e3o, dona de casa, esse tipo de coisa. E, ainda assim, na gastronomia o que mais se encontra s\u00e3o homens, chefs de cozinha e donos de restaurante, porque a cozinha s\u00f3 \u00e9 lugar de mulher quando se \u00e9 amadora, porque profissional mesmo, s\u00f3 o homem.<\/p>\n\n\n\n<p>Com a escrita acaba sendo a mesma l\u00f3gica. Diariamente livros e hist\u00f3rias escritas por mulheres s\u00e3o alvos de cr\u00edticas que nada est\u00e3o relacionadas ao enredo em si, e sim ao fato de serem escritas por mulheres. E que isso justificaria a falta de habilidade no enla\u00e7ar da trama. Justificativas chulas de que as hist\u00f3rias n\u00e3o s\u00e3o v\u00e1lidas por conta da pouca idade de quem as escreve, de que n\u00e3o s\u00e3o hist\u00f3rias de verdade e de que existem milh\u00f5es de outros livros que merecem mais aten\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Se tem uma coisa que aprendi desde a minha adolesc\u00eancia explorando o mundo liter\u00e1rio virtual, \u00e9 que escritora de fanfic consegue se unir e virar uma coisa enorme, tal qual um Transformer.&nbsp;<\/p>\n\n\n\n<p>E, apesar do t\u00edtulo deste artigo, n\u00e3o \u00e9 de qualquer literatura er\u00f3tica que eu vim falar.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fanfics e erotismo<\/h2>\n\n\n\n<p>Depois de um tempo como hist\u00f3rias inocentes e divertidas, as fanfics cresceram em g\u00eanero e idade, assim como quem as escreve. Meninas que outrora escreviam sobre romances \u00e1gua com a\u00e7\u00facar com seus \u00eddolos de banda agora se tornaram mulheres espalhando seus desejos, d\u00favidas e curiosidades nessas hist\u00f3rias. Arrisco dizer que foi assim que nasceu a literatura er\u00f3tica atual. Tenho esse pensamento porque, caso voc\u00ea n\u00e3o saiba, Cinquenta Tons de Cinza era uma fanfic da Saga Crep\u00fasculo.<\/p>\n\n\n\n<p>E.L. James, autora de Cinquenta Tons, era muito f\u00e3 da saga de Stephenie Meyer. \u00c9 claro que por conta de direitos autorais, todos os personagens tiveram de ser reformulados, mas se voc\u00ea prestar bem aten\u00e7\u00e3o h\u00e1 uma ineg\u00e1vel liga\u00e7\u00e3o entre Edward Cullen e Christian Grey, entre Ana Steele e Bella Swan.&nbsp;<\/p>\n\n\n\n<p>Os livros er\u00f3ticos existiam muito antes disso, mas foi com E.L. James que pipocou um novo jeito de escrever sobre personagens, sobre fic\u00e7\u00e3o de f\u00e3 e tamb\u00e9m sobre personagens originais. Fez tanto sucesso que muita gente n\u00e3o entendeu exatamente sobre o que se tratava, pensando ser s\u00f3 mais uma febre de livros. Eu me lembro de comprar Cinquenta Tons de Cinza em uma Bienal e ficar escandalizada com a leitura. Eu era menor de idade. Eu nunca tinha lido um livro er\u00f3tico na vida. Eu achei a leitura muito diferente do que qualquer coisa que eu estava acostumada a ler e n\u00e3o peguei no livro por semanas, me sentindo enganada. No fim das contas, presenteei minha m\u00e3e com o meu exemplar de Cinquenta Tons (e ela adorou).<\/p>\n\n\n\n<p>Nascia ali um novo segmento na literatura dita como feminina, e livros assim fazem sucesso at\u00e9 hoje. Quando disse que o submundo das fanfics (e originais!) \u00e9 um universo a ser explorado com afinco, quis dizer que existem livros que s\u00e3o verdadeiros best-sellers e que muito senso comum nem sonha que existe.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Literatura er\u00f3tica de mulheres para mulheres<\/h2>\n\n\n\n<p>A literatura er\u00f3tica escrita <a rel=\"noreferrer noopener\" aria-label=\"por mulheres para mulheres (abre numa nova aba)\" href=\"https:\/\/xplastic.com.br\/mulheres-fazendo-porno-elas-sao-as-protagonistas\/\" target=\"_blank\">por mulheres para mulheres<\/a> e para nichos muito \u00fanicos, acaba sendo parte de uma emancipa\u00e7\u00e3o do pr\u00f3prio mercado liter\u00e1rio. \u00c9 quase como um Clube da Luluzinha, no melhor sentido da compara\u00e7\u00e3o, de t\u00e3o unidas que autoras e leitoras s\u00e3o. Nos livros, a sexualidade da mulher h\u00e9tero \u2014 e \u00e9 importante frisar isso \u2014 \u00e9 explorada dos mais diversos jeitos, passando por tramas de suspense, mist\u00e9rio, envoltos <a href=\"https:\/\/xplastic.com.br\/mulheres-fazendo-pornografia-sexo-hard-e-bdsm\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"em BDSM (abre numa nova aba)\">em BDSM<\/a> e em homens poderosos como fonte de desejo.<\/p>\n\n\n\n<p>Embora eu ache v\u00e1lida a import\u00e2ncia dessas hist\u00f3rias, n\u00e3o posso deixar de criticar alguns pontos chave que devem ser observados com cuidado: Se voc\u00ea buscar por \u201cromances hot\u201d na <a href=\"https:\/\/www.amazon.com.br\/romance-hot-Livros\/s?k=romance+hot&amp;rh=n%3A7882388011\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Amazon<\/a>, que \u00e9 como s\u00e3o classificados esses livros, quase todas as capas ser\u00e3o iguais. Um homem branco, padr\u00e3o, sarado e meio pelado, segurando uma mulher branca, padr\u00e3o, sarada e meio pelada. Quando n\u00e3o s\u00e3o apenas capas com o tronco dos homens exibindo tanquinhos perfeitos, e eu n\u00e3o estou exagerando: os <em>cinco<\/em> primeiros livros que aparecem na categoria durante minha pesquisa tem capas assim, muito parecidas entre si.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica-1024x683.jpg\" alt=\"Foto er\u00f3tica em PB - mulher sentada no colo de um cara - literatura er\u00f3tica\" class=\"wp-image-8100\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica.jpg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica-512x342.jpg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> Imagem: Pixabay. Essa imagem \u00e9 livre de direitos autorais e est\u00e1 em muitas das capas de livros vendidos na Amazon. <\/figcaption><\/figure><\/div>\n\n\n\n<p>\u00c9 muito bom que a sexualidade da mulher h\u00e9tero seja explorada na literatura, porque de fato a mulher h\u00e9tero \u00e9 uma das menos favorecidas em quest\u00e3o de prazer sexual. Sucumbindo a desejos masculinos h\u00e1 s\u00e9culos, \u00e9 bom que pelo menos em algum lugar, seus desejos sejam os mais importantes. Mas n\u00e3o deixa de me incomodar que a Mulher H\u00e9tero dessas hist\u00f3rias seja a Mulher Padr\u00e3o.<\/p>\n\n\n\n<p>Quando n\u00e3o \u00e9 a Mulher Padr\u00e3o, configuram tamb\u00e9m romances LGBT entre homens, Dois Homens Padr\u00e3o. O romance hot gay est\u00e1 na lista dos mais consumidos do segmento tamb\u00e9m, logo atr\u00e1s das hist\u00f3rias protagonizadas por casais h\u00e9teros. Apesar da diferen\u00e7a entre sexualidades, as hist\u00f3rias tendem a seguir mais ou menos os mesmos moldes. Nesse caso, destaco ainda que muitas autoras pecam em fetichizar rela\u00e7\u00f5es homossexuais, caindo em clich\u00eas que deixam de ser saud\u00e1veis e passam a ser problem\u00e1ticos.<\/p>\n\n\n\n<p>Inclusive, esse tipo de hist\u00f3ria com pessoas que n\u00e3o sejam padr\u00e3o est\u00e1 t\u00e3o em falta que n\u00e3o consigo pontuar nenhuma para dar o exemplo de como as coisas poderiam ser feitas. O que \u00e9, de fato, extremamente bizarro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Romances hot<\/h2>\n\n\n\n<p>O mais interessante \u00e9 que na Amazon e no Wattpad, as mulheres brasileiras dominam esse segmento. Autoras de romances hot seguem sendo as mais vendidas de e-books da Amazon, e figuram nas listas de mais lidos do Kindle Unlimited, programa de assinaturas do site que permite que voc\u00ea leia livros por um pequeno valor mensal. J\u00e1 no Wattpad, site conhecido pelas fanfics e por hist\u00f3rias originais publicadas pelo pr\u00f3prio autor, a literatura er\u00f3tica para mulheres consegue alcan\u00e7ar a almejada marca de um milh\u00e3o de leituras facilmente. \u201cFacilmente\u201d no sentido de rapidez, uma vez que livros assim n\u00e3o demoram muito mais do que seis meses para ganhar as visualiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 um trabalho simples. Divulgar livros que ainda n\u00e3o foram impressos \u00e9 t\u00e3o complicado que autoras criaram grupos do Facebook e uma rede de divulga\u00e7\u00e3o de seus livros. A postagem \u00e9 massiva, s\u00e3o v\u00e1rios grupos bombardeados todos os dias com imagens e trechos das hist\u00f3rias, tudo para cativar as futuras leitoras e encontrar vendas para a Amazon e visualiza\u00e7\u00f5es para o Wattpad.<\/p>\n\n\n\n<p>At\u00e9 existem escritores de romances hot h\u00e9tero que s\u00e3o homens, mas a quantidade \u00e9 pequena e muitas vezes o p\u00fablico n\u00e3o os aprova, uma vez que tendem a diminuir a sexualidade feminina para expandir a masculina. Assim, perdendo todo o ponto do segmento, na minha opini\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hist\u00f3rias de mulherzinha?<\/h2>\n\n\n\n<p>E como a quantidade de livros \u00e9 imensa e tem cenas de sexo em todos eles, as autoras se viram do avesso para criar tramas complexas e elaboradas que prendam a aten\u00e7\u00e3o das leitoras. Para isso o c\u00e9u \u00e9 o limite, levando a tramas envoltas em m\u00e1fia, assassinatos, mentiras, fantasia urbana e fic\u00e7\u00e3o cient\u00edfica. Apesar das diferen\u00e7as de enredo, os romances h\u00e9tero seguem uma receita em comum na maioria das vezes: os personagens masculinos s\u00e3o homens poderosos, CEOs ou donos de imp\u00e9rios e extremamente misteriosos, com passados sombrios e que a mocinha inocente n\u00e3o tem a menor ideia de onde est\u00e1 se metendo, mas n\u00e3o consegue deixar de se sentir atra\u00edda por ele.&nbsp;<\/p>\n\n\n\n<p>O sucesso \u00e9 o que sustenta um clich\u00ea, e se deu certo para v\u00e1rios, provavelmente vai dar certo para os outros, \u00e9 verdade. Mas n\u00e3o se engane com as minhas compara\u00e7\u00f5es, se fossem livros iguais, eles n\u00e3o seriam t\u00e3o populares. O que mant\u00e9m o segmento como t\u00e3o vasto \u00e9 justamente a originalidade que cada autora consegue inserir em seu enredo.<br>S\u00e3o milhares de visualiza\u00e7\u00f5es e milhares de vendas, e muitas vezes nas lojas de e-book os livros ultrapassam best-sellers como Harry Potter e outros livros internacionalmente famosos. N\u00e3o acredita? \u00c9 s\u00f3 ver a <a href=\"https:\/\/www.amazon.com.br\/gp\/bestsellers\/digital-text\/5475882011\/ref=s9_acss_bw_h1_KBHPtest_md2_w?pf_rd_m=A3RN7G7QC5MWSZ&amp;pf_rd_s=merchandised-search-1&amp;pf_rd_r=09BADMWYE42MMZAAPY2T&amp;pf_rd_t=101&amp;pf_rd_p=afd13151-813b-465f-977f-31fbb82374d8&amp;pf_rd_i=5475882011\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">lista de mais vendidos<\/a> da loja e-Book Kindle na Amazon.  <\/p>\n\n\n\n<p>Enquanto autores homens, h\u00e9teros cis e brancos est\u00e3o por a\u00ed criticando mulheres que vieram das fanfics, elas arranjaram um jeito de criar p\u00fablicos enormes e uma forma de viver da escrita, chegando a fazer encontros em Bienais de Livro e a figurar na lista de mais vendidos, enquanto muitos desses homens, h\u00e9teros cis e brancos ainda esperam uma publica\u00e7\u00e3o de suas obras que eles juram ser a melhor coisa do mundo, muito melhor do que essas \u201chist\u00f3rias pra mulherzinha\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando mandei meu primeiro email para a Xplastic a fim de preencher a vaga de escritor para este blog, precisei mostrar um pouco de mim,&#8230;<\/p>\n","protected":false},"author":16,"featured_media":8100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-8098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportagens"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie<\/title>\n<meta name=\"description\" content=\"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie\" \/>\n<meta property=\"og:description\" content=\"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\" \/>\n<meta property=\"og:site_name\" content=\"Xplastic Altporn\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-27T19:20:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T17:37:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nittie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ofnittie\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nittie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\"},\"author\":{\"name\":\"Nittie\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/dc0cc3712630d34b09893413b667c125\"},\"headline\":\"A literatura er\u00f3tica que ainda n\u00e3o foi impressa\",\"datePublished\":\"2019-11-27T19:20:58+00:00\",\"dateModified\":\"2020-02-26T17:37:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\"},\"wordCount\":1830,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"articleSection\":[\"Reportagens\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\",\"name\":\"A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\"},\"datePublished\":\"2019-11-27T19:20:58+00:00\",\"dateModified\":\"2020-02-26T17:37:33+00:00\",\"description\":\"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica\",\"breadcrumb\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/xplastic.lv.localhost\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A literatura er\u00f3tica que ainda n\u00e3o foi impressa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"name\":\"Xplastic Altporn\",\"description\":\"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!\",\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\",\"name\":\"X-Plastic Altporn\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"X-Plastic Altporn\"},\"image\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/dc0cc3712630d34b09893413b667c125\",\"name\":\"Nittie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/d8d0f254283102b9e2b2ebd32f88fe78.jpg?ver=1778421349\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/d8d0f254283102b9e2b2ebd32f88fe78.jpg?ver=1778421349\",\"caption\":\"Nittie\"},\"description\":\"Escritora de hist\u00f3rias de terror, fantasia &amp; outras coisinhas mais, entusiasta da cultura geek e amante de gifs de gatinhos. Resolvi ser modelo pra aprender a fazer car\u00e3o. (N\u00e3o que tenha dado muito certo.)\",\"sameAs\":[\"https:\/\/www.instagram.com\/ofnittie\/\",\"https:\/\/twitter.com\/ https:\/\/twitter.com\/ofnittie\"],\"url\":\"https:\/\/xplastic.com.br\/blog\/author\/pixie\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie","description":"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/","og_locale":"pt_BR","og_type":"article","og_title":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie","og_description":"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica","og_url":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/","og_site_name":"Xplastic Altporn","article_published_time":"2019-11-27T19:20:58+00:00","article_modified_time":"2020-02-26T17:37:33+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/11\/foto-er\u00f3tica.jpg","type":"image\/jpeg"}],"author":"Nittie","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ofnittie","twitter_misc":{"Escrito por":"Nittie","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#article","isPartOf":{"@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/"},"author":{"name":"Nittie","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/dc0cc3712630d34b09893413b667c125"},"headline":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa","datePublished":"2019-11-27T19:20:58+00:00","dateModified":"2020-02-26T17:37:33+00:00","mainEntityOfPage":{"@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/"},"wordCount":1830,"commentCount":0,"publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"articleSection":["Reportagens"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/","url":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/","name":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa | por Nittie","isPartOf":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#website"},"datePublished":"2019-11-27T19:20:58+00:00","dateModified":"2020-02-26T17:37:33+00:00","description":"fanfics s\u00e3o hist\u00f3rias escritas por jovens sobre encontros com \u00eddolos e outros desejos adolescentes. Mas a mudan\u00e7a na escrita deu origem \u00e0 literatura er\u00f3tica","breadcrumb":{"@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xplastic.com.br\/blog\/literatura-erotica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xplastic.com.br\/blog\/literatura-erotica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/xplastic.lv.localhost\/blog\/"},{"@type":"ListItem","position":2,"name":"A literatura er\u00f3tica que ainda n\u00e3o foi impressa"}]},{"@type":"WebSite","@id":"https:\/\/xplastic.lv.localhost\/blog\/#website","url":"https:\/\/xplastic.lv.localhost\/blog\/","name":"Xplastic Altporn","description":"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!","publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization","name":"X-Plastic Altporn","url":"https:\/\/xplastic.lv.localhost\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","width":2048,"height":1365,"caption":"X-Plastic Altporn"},"image":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/dc0cc3712630d34b09893413b667c125","name":"Nittie","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/d8d0f254283102b9e2b2ebd32f88fe78.jpg?ver=1778421349","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/d8d0f254283102b9e2b2ebd32f88fe78.jpg?ver=1778421349","caption":"Nittie"},"description":"Escritora de hist\u00f3rias de terror, fantasia &amp; outras coisinhas mais, entusiasta da cultura geek e amante de gifs de gatinhos. Resolvi ser modelo pra aprender a fazer car\u00e3o. (N\u00e3o que tenha dado muito certo.)","sameAs":["https:\/\/www.instagram.com\/ofnittie\/","https:\/\/twitter.com\/ https:\/\/twitter.com\/ofnittie"],"url":"https:\/\/xplastic.com.br\/blog\/author\/pixie\/"}]}},"_links":{"self":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/8098"}],"collection":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8098"}],"version-history":[{"count":0,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/8098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media\/8100"}],"wp:attachment":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}