{"id":3141,"date":"2016-07-28T20:18:44","date_gmt":"2016-07-28T23:18:44","guid":{"rendered":"https:\/\/xplastic.com.br\/?p=3141"},"modified":"2019-11-18T14:59:19","modified_gmt":"2019-11-18T17:59:19","slug":"pai-e-filho-pornolandia","status":"publish","type":"post","link":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/","title":{"rendered":"Eduardo Azevedo e Junior &#8211; Pai e filho na pornografia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-1024x683.jpeg\" alt=\"Pai e filho na Pornografia com Nicole Puzzi\" class=\"wp-image-3254\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-1024x683.jpeg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-512x341.jpeg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-768x512.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Neste epis\u00f3dio Nicole Puzzi entrevista <strong>Eduardo Azevedo e Junior<\/strong>, pai e filho na pornografia. No epis\u00f3dio 8 da terceira temporada de <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/xplastic.com.br\/pornolandia-nosso-programa-canal-brasil\/\" target=\"_blank\">Pornol\u00e2ndia<\/a> eles conversam sobre o in\u00edcio na pornografia, hist\u00f3rias engra\u00e7adas de grava\u00e7\u00f5es e como surgiu o site Turma do Sexo. Uma conversa divertida que voc\u00ea poder\u00e1 ler na transcri\u00e7\u00e3o a seguir, ou assistir diretamente no Canal Brasil na <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/globosatplay.globo.com\/canal-brasil\/pornolandia\/\" target=\"_blank\">Globoplay<\/a>.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-2-1024x683.jpeg\" alt=\"Eduardo Azevedo e Junior - pai e filho na pornografia entrevistados por Nicole \" class=\"wp-image-3255\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-2-1024x683.jpeg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-2-512x341.jpeg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-2-768x512.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho-2.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Nicole Puzzi: A frase &#8220;tal pai, tal filho&#8221; nunca caiu t\u00e3o bem quanto para esses dois malucos! Eles s\u00e3o os criadores, produzem e dirigem o site<em> Turma do Sexo<\/em>. Hoje, a nossa conversa ser\u00e1 com o Edu Azevedo e com Junior, pai e filho na pornografia. E a Xgirl de hoje vai terminar o nosso papo deixando tudo ainda mais quente!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem levou quem para o mau caminho<\/h2>\n\n\n\n<p><strong>Edu e Junior. Pai e filho. Eu nunca imaginei que eu fosse entrevistar pai e filho pornogr\u00e1ficos! Estou adorando. Mas, quem levou quem para o mau caminho? O pai?<\/strong><\/p>\n\n\n\n<p>Junior: Ele come\u00e7ou!<\/p>\n\n\n\n<p><strong>NP: Safado!!!<\/strong><\/p>\n\n\n\n<p>Eduardo Azevedo. Bem no in\u00edcio, n\u00e9.<\/p>\n\n\n\n<p><strong>NP: A\u00ed, voc\u00ea falou &#8220;filho, vamos, est\u00e1 bom aqui&#8221;?<\/strong><\/p>\n\n\n\n<p>Eduardo Azevedo: O Junior sabia desde pequeno com o que eu trabalhava e sempre queria ir a um set de grava\u00e7\u00e3o. <\/p>\n\n\n\n<p><strong>NP: Sim, claro!<\/strong><\/p>\n\n\n\n<p>Junior: Curiosidade!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pai e filho na pornografia<\/h2>\n\n\n\n<p>EA: E ele conhecia muitas atrizes que iam em casa. Ia fazer um churrasco em casa, elas iam, iam atores e atrizes. Ent\u00e3o, ele j\u00e1 tinha muito conhecimento sobre esse meio. Ele fez anivers\u00e1rio de 18 anos em um s\u00e1bado, no domingo a gente foi gravar e ele j\u00e1 foi conosco. Come\u00e7ou com 18 anos e um dia.<\/p>\n\n\n\n<p><strong>NP: Ah, legal!<\/strong><\/p>\n\n\n\n<p>JU: A\u00ed, eu j\u00e1 podia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A trajet\u00f3ria de Edu no porn\u00f4<\/h2>\n\n\n\n<p><strong>NP: Ah, a\u00ed j\u00e1 podia, n\u00e9. E a sua trajet\u00f3ria, Edu, como voc\u00ea come\u00e7ou nesse mundo?<\/strong><\/p>\n\n\n\n<p>EA: Eu comecei com 18 anos tamb\u00e9m. <\/p>\n\n\n\n<p><strong>NP: Tamb\u00e9m?<\/strong><\/p>\n\n\n\n<p>EA: S\u00f3 que eu comecei na Rua Aurora, no teatro Odeon na \u00e9poca.<\/p>\n\n\n\n<p><strong>NP: Sim!<\/strong><\/p>\n\n\n\n<p>EA: Eu fazia um show, um espet\u00e1culo, uma com\u00e9dia er\u00f3tica que tinha sexo expl\u00edcito.<\/p>\n\n\n\n<p><strong>NP: E voc\u00ea fazia sexo expl\u00edcito no palco?<\/strong><\/p>\n\n\n\n<p>EA: Sim. Eu comecei como ator, eu era escada do Vit\u00f3rio Milani apenas na comicidade. Em um belo dia, o ator que fazia o sexo expl\u00edcito pegou a mulher dele l\u00e1 e foi embora e n\u00e3o tinha outro ator para fazer em outra sess\u00e3o, porque eram 5 sess\u00f5es por dia. A\u00ed, o diretor falou &#8220;vai voc\u00ea&#8221;. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O vexame<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-683x1024.jpeg\" alt=\"Nicole Puzzi, entrevistadora do Pornol\u00e2ndia\" class=\"wp-image-3256\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-683x1024.jpeg 683w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-341x512.jpeg 341w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-768x1152.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho.jpeg 1000w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure><\/div>\n\n\n\n<p><strong>NP: E a\u00ed, voc\u00ea entrou no palco, pelado, como \u00e9 que foi? <\/strong><\/p>\n\n\n\n<p>EA: \u00c9 uma historinha de escrit\u00f3rio. Tinha a secret\u00e1ria que se insinuava para o officeboy e eu era o officeboy. E para mim era uma grande novidade, eu s\u00f3 sabia o texto dele porque eu atuava com ele como c\u00f4mico e, de repente, eu passei a ser o gal\u00e3.  A adrenalina sobe, o cora\u00e7\u00e3o dispara, um monte de gente ansioso para ver voc\u00ea atuando, ver voc\u00ea funcionando com uma mulher linda e maravilhosa. E o vexame foi total. <\/p>\n\n\n\n<p><strong>NP: O de cima subiu e o de baixo desceu!<\/strong><\/p>\n\n\n\n<p>EA: N\u00e3o, sumiu! Nem desce, nem sobe. <\/p>\n\n\n\n<p><strong>NP: Gente!!! Broxada total&#8230;<\/strong><\/p>\n\n\n\n<p>EA: A minha primeira broxada da vida com 400 testemunhos. Ou seja, foi muito&#8230; Sa\u00ed de l\u00e1 com a cabe\u00e7a pirada! <\/p>\n\n\n\n<p><strong>NP: E quando \u00e9 que foi a primeira vez que subiu, porque naquela \u00e9poca n\u00e3o tinha viagra! N\u00e3o era f\u00e1cil.<\/strong><\/p>\n\n\n\n<p>EA: N\u00e3o tinha viagra! <\/p>\n\n\n\n<p><strong>NP: O ator porn\u00f4 tinha que ser poderoso!<\/strong><\/p>\n\n\n\n<p>EA: Tinha que ser na ra\u00e7a! Eu tentei e sa\u00ed ovacionado&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reviravolta<\/h2>\n\n\n\n<p><strong>NP: Por que n\u00e3o tinha subido?<\/strong><\/p>\n\n\n\n<p>EA: Tomei vaia, sapatada. Algu\u00e9m na plateia saiu sem sapato, porque jogaram um em mim no palco. No dia seguinte, eu voltei para pedir as contas, porque eu n\u00e3o ia passar um vexame desse de novo. Cheguei l\u00e1 e falei &#8216;estou pedido minha demiss\u00e3o, eu n\u00e3o sirvo para a coisa e n\u00e3o d\u00e1 certo&#8221;. Porque, o meu pau n\u00e3o funcionou, o palco me travou. O diretor pegou e falou &#8220;faz mais uma broxada e vai embora&#8221;.<\/p>\n\n\n\n<p><strong>NP: D\u00e1 mais uma broxada e vai embora!<\/strong><\/p>\n\n\n\n<p>EA: D\u00e1 mais uma broxada, pelo menos o pessoal vai dar risada, jogam o sapato em voc\u00ea&#8230;<\/p>\n\n\n\n<p><strong>NP: Seu filho est\u00e1 rindo de voc\u00ea!<\/strong><\/p>\n\n\n\n<p>EA: E vai embora seu tranqueira! Na cabe\u00e7a, eu pensei assim &#8220;eu n\u00e3o tenho obriga\u00e7\u00e3o de ter uma ere\u00e7\u00e3o&#8221; e entrei. E a menina tamb\u00e9m, eu pedi para ele me ajudar e ela disse &#8220;n\u00e3o sou Deus para fazer milagre, ele sumiu&#8221;. Ent\u00e3o, ela ia entrar preparada para mais um vexame e ela olhou e falou &#8220;subiu&#8221;. Eu olhei, nossa, ascende a luz, vamos! Acho que aquilo quebrou meu medo, acabou a inseguran\u00e7a e eu consegui relaxar e fazer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Junior no Porn\u00f4<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-3-1024x683.jpeg\" alt=\"Cam\u00eara focando em Nicole Puzzi que entrevista pai e filho na pornografia\" class=\"wp-image-3257\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-3-1024x683.jpeg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-3-512x341.jpeg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-3-768x512.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-3.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>NP: E voc\u00ea, Junior? Voc\u00ea, jovem, como voc\u00ea acha que pode contribuir pra a ind\u00fastria, porque \u00e9 uma ind\u00fastria muito marginalizada.   <\/strong><\/p>\n\n\n\n<p>JU: Sim, hoje em dia \u00e9. Ah, eu acho que uma vis\u00e3o diferente, n\u00e9, tentar fazer as pessoas enxergarem mais a arte do sexo, do porn\u00f4, que o pessoal n\u00e3o mistura muito hoje em dia.<\/p>\n\n\n\n<p><strong>NP: Junior, eu entrei no seu site e vi um rapaz de gorro, \u00f3culos escuros. Eu achei t\u00e3o parecido com voc\u00ea.<\/strong><\/p>\n\n\n\n<p>JU: N\u00e3o. Vai que eu tenho um irm\u00e3o por a\u00ed perdido. <\/p>\n\n\n\n<p>EA: Que eu saiba n\u00e3o!<\/p>\n\n\n\n<p>JU: Perdido? A\u00ed tem que ver com ele.<\/p>\n\n\n\n<p><strong>NP: E voc\u00ea, Junior, j\u00e1 sofreu algum preconceito quando as pessoas descobrem que voc\u00ea faz filme porn\u00f4, produz e dirige?<\/strong><\/p>\n\n\n\n<p>JU: Ah, j\u00e1 vi bastante gente falando &#8220;nossa, que estranho&#8221;, &#8220;meu, como assim, me explica direito&#8221;. Tem gente que n\u00e3o acredita, tem gente que fala &#8220;ah, voc\u00ea \u00e9 safado&#8221; porque eu trabalho com isso. Ent\u00e3o, j\u00e1 teve gente que eu estava conhecendo e eu falei que fazia isso a\u00ed j\u00e1 ficou mais estranho. J\u00e1 aconteceu, at\u00e9 a\u00ed&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pai e filho na pornografia &#8211; Turma do Sexo<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-2-1024x683.jpeg\" alt=\"Nicole Puzzi de vestido vermelho\" class=\"wp-image-3258\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-2-1024x683.jpeg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-2-512x341.jpeg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-2-768x512.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/nicole-pai-e-filho-2.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>NP: E a Turma do Sexo, como \u00e9 que surgiu? O que \u00e9 Turma do Sexo?<\/strong><\/p>\n\n\n\n<p>EA: Foi assim, eu j\u00e1 tinha me afastado do mundo porn\u00f4, estava em um &#8220;trabalho normal&#8221; e parece que vem uma tenta\u00e7\u00e3o de um s\u00f3cio e um compadre meu. &#8220;Olha, comprei uma c\u00e2mera. Vamos gravar uma coisa? Eu conhe\u00e7o uma menina muito legal! Vamos fazer uma bagun\u00e7a, nada programado, deixa rolar, vamos passar a c\u00e2mara um para o outro e cada um grava um pouquinho&#8221;. Fizemos uma, fizemos duas e eu pensei &#8220;a gente podia montar um site&#8221;. A\u00ed, n\u00f3s come\u00e7amos a gravar e a guardar. Come\u00e7amos a chamar meninas, gravar e guardar esse material durante tr\u00eas anos. O material foi acumulando, s\u00f3 que no in\u00edcio n\u00e3o tinham meninas que queriam participar, porque nem cach\u00ea n\u00f3s t\u00ednhamos. Ent\u00e3o, era amiga, a dentista do meu s\u00f3cio&#8230;<\/p>\n\n\n\n<p><strong>NP: A dentista? <\/strong><\/p>\n\n\n\n<p>EA: Sim. Uma menina que trabalhava no bairro l\u00e1. Coloc\u00e1vamos m\u00e1scara e &#8220;Vamos gravar? N\u00e3o vai mostrar seu rosto&#8221;. E grav\u00e1vamos! Quando a gente viu, est\u00e1vamos com um arquivo muito legal. Foi a\u00ed que convidamos Nathaly Bueno, M\u00f4nica Mattos e come\u00e7amos a mesclar. A gente n\u00e3o queria que elas come\u00e7assem a atuar como nos filmes convencionais, n\u00f3s quer\u00edamos que elas fossem elas mesmas, sem dire\u00e7\u00e3o. Tipo &#8220;fa\u00e7a o que quiser&#8221; e \u00e9 um projeto super legal. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hist\u00f3rias de grava\u00e7\u00e3o<\/h2>\n\n\n\n<p><strong>NP: Voc\u00ea fez uma coisa que voc\u00ea me contou em off que eu queria que voc\u00ea falasse. Voc\u00ea n\u00e3o tinha o viagra no momento, o que voc\u00ea fez? Me conta essa hist\u00f3ria.<\/strong><\/p>\n\n\n\n<p>EA: Est\u00e1vamos em uma grava\u00e7\u00e3o e acabou o viagra, n\u00e9. Eu olhei para o produtor e acabou o viagra, o ator est\u00e1 querendo para poder trabalhar. Ele abriu uma bolsinha dele, pegou um comprimido qualquer&#8230;<\/p>\n\n\n\n<p><strong>NP: Um AS.<\/strong><\/p>\n\n\n\n<p>EA: Um AS da vida e deu para o ator. O ator olhou assim e disse &#8220;isso n\u00e3o \u00e9 viagra&#8221;. Eu falei &#8220;\u00e9 viagra tailand\u00eas, s\u00f3 que \u00e9 muito forte, vou cortar metade e voc\u00ea s\u00f3 toma metade&#8221;. Ele tomou um dicloflenaco d vida e fez uma cena sensacional. &#8220;Voc\u00ea n\u00e3o tem um desse para me vender?&#8221;. <\/p>\n\n\n\n<p><strong>NP: Agora, eu quero agradecer a presen\u00e7a de voc\u00eas. Obrigada, pai, muito obrigada, filho. Adorei!!!<\/strong><\/p>\n\n\n\n<p>EA: N\u00f3s que agradecemos o espa\u00e7o, a oportunidade.<\/p>\n\n\n\n<p><strong>NP: Obrigada! E agora n\u00f3s vamos conhecer uma mulher maravilhosa, a nossa Xgirl. <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A nossa Xgirl<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz-1024x570.jpeg\" alt=\"Xgirl Patricia Ferraz\" class=\"wp-image-3260\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz-1024x570.jpeg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz-512x285.jpeg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz-768x428.jpeg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz-630x350.jpeg 630w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/patricia-ferraz.jpeg 1867w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>E o programa terminou com a maravilhosa Xgirl<strong> <a href=\"https:\/\/xplasticstage.wpengine.com\/patricia-ferraz\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Patricia Ferraz (abre numa nova aba)\">Patricia Ferraz<\/a><\/strong>, uma loira linda e gostosa, que ficou nua em um ensaio sensual que vai te enlouquecer!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste epis\u00f3dio Nicole Puzzi entrevista Eduardo Azevedo e Junior, pai e filho na pornografia. No epis\u00f3dio 8 da terceira temporada de Pornol\u00e2ndia eles conversam sobre&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-3141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pornolandia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eduardo Azevedo e Junior - Pai e filho na pornografia<\/title>\n<meta name=\"description\" content=\"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eduardo Azevedo e Junior - Pai e filho na pornografia\" \/>\n<meta property=\"og:description\" content=\"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\" \/>\n<meta property=\"og:site_name\" content=\"Xplastic Altporn\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-28T23:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-18T17:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"xplastic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"xplastic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\"},\"author\":{\"name\":\"xplastic\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/345ea20678630d5db42b44e5aa69954b\"},\"headline\":\"Eduardo Azevedo e Junior &#8211; Pai e filho na pornografia\",\"datePublished\":\"2016-07-28T23:18:44+00:00\",\"dateModified\":\"2019-11-18T17:59:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\"},\"wordCount\":1478,\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"articleSection\":[\"Pornol\u00e2ndia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\",\"name\":\"Eduardo Azevedo e Junior - Pai e filho na pornografia\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\"},\"datePublished\":\"2016-07-28T23:18:44+00:00\",\"dateModified\":\"2019-11-18T17:59:19+00:00\",\"description\":\"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.\",\"breadcrumb\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/xplastic.lv.localhost\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eduardo Azevedo e Junior &#8211; Pai e filho na pornografia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"name\":\"Xplastic Altporn\",\"description\":\"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!\",\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\",\"name\":\"X-Plastic Altporn\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"X-Plastic Altporn\"},\"image\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/345ea20678630d5db42b44e5aa69954b\",\"name\":\"xplastic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/ed2e87afc9bcdeb2bb6a129f00105799.jpg?ver=1778466125\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/ed2e87afc9bcdeb2bb6a129f00105799.jpg?ver=1778466125\",\"caption\":\"xplastic\"},\"url\":\"https:\/\/xplastic.com.br\/blog\/author\/sadminxplastic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eduardo Azevedo e Junior - Pai e filho na pornografia","description":"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/","og_locale":"pt_BR","og_type":"article","og_title":"Eduardo Azevedo e Junior - Pai e filho na pornografia","og_description":"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.","og_url":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/","og_site_name":"Xplastic Altporn","article_published_time":"2016-07-28T23:18:44+00:00","article_modified_time":"2019-11-18T17:59:19+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/pai-e-filho.jpeg","type":"image\/jpeg"}],"author":"xplastic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"xplastic","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#article","isPartOf":{"@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/"},"author":{"name":"xplastic","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/345ea20678630d5db42b44e5aa69954b"},"headline":"Eduardo Azevedo e Junior &#8211; Pai e filho na pornografia","datePublished":"2016-07-28T23:18:44+00:00","dateModified":"2019-11-18T17:59:19+00:00","mainEntityOfPage":{"@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/"},"wordCount":1478,"publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"articleSection":["Pornol\u00e2ndia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/","url":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/","name":"Eduardo Azevedo e Junior - Pai e filho na pornografia","isPartOf":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#website"},"datePublished":"2016-07-28T23:18:44+00:00","dateModified":"2019-11-18T17:59:19+00:00","description":"Eles s\u00e3o pai e filho e trabalham juntos com pornografia. Eduardo Azevedo e Junior falam ao Pornol\u00e2ndia sobre a rela\u00e7nao familiar no set.","breadcrumb":{"@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xplastic.com.br\/blog\/pai-e-filho-pornolandia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/xplastic.lv.localhost\/blog\/"},{"@type":"ListItem","position":2,"name":"Eduardo Azevedo e Junior &#8211; Pai e filho na pornografia"}]},{"@type":"WebSite","@id":"https:\/\/xplastic.lv.localhost\/blog\/#website","url":"https:\/\/xplastic.lv.localhost\/blog\/","name":"Xplastic Altporn","description":"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!","publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization","name":"X-Plastic Altporn","url":"https:\/\/xplastic.lv.localhost\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","width":2048,"height":1365,"caption":"X-Plastic Altporn"},"image":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/345ea20678630d5db42b44e5aa69954b","name":"xplastic","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/ed2e87afc9bcdeb2bb6a129f00105799.jpg?ver=1778466125","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/ed2e87afc9bcdeb2bb6a129f00105799.jpg?ver=1778466125","caption":"xplastic"},"url":"https:\/\/xplastic.com.br\/blog\/author\/sadminxplastic\/"}]}},"_links":{"self":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/3141"}],"collection":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3141"}],"version-history":[{"count":0,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/3141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media\/3254"}],"wp:attachment":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}