{"id":3103,"date":"2020-02-13T21:23:00","date_gmt":"2020-02-14T00:23:00","guid":{"rendered":"https:\/\/xplastic.com.br\/?p=3103"},"modified":"2020-02-26T14:37:09","modified_gmt":"2020-02-26T17:37:09","slug":"podolatria-feminina-podolatria-lesbica","status":"publish","type":"post","link":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/","title":{"rendered":"Podolatria feminina e a Hist\u00f3ria de P."},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-1024x574.jpg\" alt=\"Brancas como leite - podolatria feminina\" class=\"wp-image-8610\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-1024x574.jpg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-512x287.jpg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-768x430.jpg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-1536x861.jpg 1536w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-100x56.jpg 100w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-700x392.jpg 700w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44-1600x897.jpg 1600w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/brancas-como-leite-44.jpg 1863w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>E ent\u00e3o&#8230; N\u00f3s, mulheres, <a href=\"https:\/\/xplastic.com.br\/blog\/descobrindo-a-podolatria\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"gostamos de pezinhos (abre numa nova aba)\">gostamos de pezinhos<\/a> tamb\u00e9m. \u00c9, rapazes&#8230; O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a lesbopodolatria (ou <a rel=\"noreferrer noopener\" aria-label=\"podolatria (abre numa nova aba)\" href=\"https:\/\/blog.safada.tv\/podolatria-com-emme-white\/\" target=\"_blank\">podolatria<\/a> feminina, como quiser). Ali\u00e1s, a descoberta do prazer em ter os p\u00e9s adorados, \u00e9 uma experi\u00eancia t\u00e3o transcedental de prazer, quanto \u00e0 primeira siririca. Tes\u00e3o total.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lesbopodolatria<\/h3>\n\n\n\n<p>Por anos e anos, confesso, duvidei de tanto tes\u00e3o expl\u00edcito em cenas de podolatria entre l\u00e9sbicas, porque meu referencial e amostragem era:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Inicialmente eu acreditava que fetiches eram exclusividade masculina (o conhecimento e o tempo mudou minha opini\u00e3o).<\/li><li>S\u00f3 quem consumia porn\u00f4 de l\u00e9sbicas em cenas pod\u00f3latras, entre si ou em cenas de Domina\u00e7\u00e3o, era o p\u00fablico masculino.<\/li><li>E porque, pessoalmente, mesmo conhecendo tantas mulheres, raras se assumiam pod\u00f3latras e l\u00e9sbicas pod\u00f3latras, menos ainda.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">A hist\u00f3ria de P. &#8211; Bissexual e Pod\u00f3latra L\u00e9sbica<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-1024x572.jpg\" alt=\"Brancas como leite - podolatria feminina\" class=\"wp-image-8611\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-1024x572.jpg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-512x286.jpg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-768x429.jpg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-1536x858.jpg 1536w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-100x56.jpg 100w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-700x391.jpg 700w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43-1600x894.jpg 1600w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-43.jpg 1863w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A verdade, \u00e9 que sem perceber EU estava sendo preconceituosa por ignor\u00e2ncia. N\u00e3o ignor\u00e2ncia grosseria, mas no sentido de desconhecer.<\/p>\n\n\n\n<p>Foi ent\u00e3o, que no in\u00edcio dos anos 2000 eu conheci a P. uma linda universit\u00e1ria, bissexual, de quase 20 anos, que guardava um segredo a sete chaves&#8230; Ela se achava bem incomum, pois &#8220;se excitava com umas coisas bobas, e outras estranhas, que envolviam p\u00e9s femininos&#8221;. E frisou: somente com os p\u00e9s de mulheres, homens s\u00f3 quero que me fodam!<\/p>\n\n\n\n<p>L\u00f3gico que fiquei curiosa, e perguntei que tipo de &#8220;coisas&#8221;. E ela comentou timidamente, sobre curtir bastante &#8220;brincar&#8221; de fazer e receber c\u00f3cegas, ou ser a pedicure das amigas, ou estar sempre massagenando os p\u00e9s das que estavam cansadas ou estressadas e, principalmente, curtia (muito) quando suas roommates brincavam de &#8220;obrig\u00e1-la&#8221; a cheirar seus p\u00e9s suados.<\/p>\n\n\n\n<p>Ou seja, a mo\u00e7a era pod\u00f3latra em N subcategorias (c\u00f3cegas, chul\u00e9, submiss\u00e3o&#8230;), e quando eu disse que todas as coisas que ela descreveu eram absolutamente comuns no contexto er\u00f3tico da podolatria, ela suspirou em al\u00edvio e me disse, que mesmo sem saber o que era podolatria, j\u00e1 estava bem mais calma em n\u00e3o ser t\u00e3o anormal, pois pensou estar louca, afinal, tudo aquilo a excitava, e muito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Podolatria, l\u00e9sbicas e o sexo<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-1024x572.jpg\" alt=\"Brancas como leite - Sweetie Bird e Mel Fire\" class=\"wp-image-8612\" srcset=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-1024x572.jpg 1024w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-512x286.jpg 512w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-768x429.jpg 768w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-1536x858.jpg 1536w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-100x56.jpg 100w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-700x391.jpg 700w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46-1600x893.jpg 1600w, https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2020\/01\/2016_BrancasComoLeite_MayaraMedeiros-46.jpg 1861w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Obviamente depois de P. passei a observar outros relatos parecidos (escrever sobre sexualidade a mais de 15 anos me deu acesso a muitas hist\u00f3rias), e mesmo em meus relacionamentos, ambos os sexos, como eu curto podolatria (fazer e receber) pude notar que n\u00e3o s\u00f3 nas preliminares era comum. Fosse beijando, acariciando, mordendo, massageando, ou mesmo penetrando&#8230;<\/p>\n\n\n\n<p>Portanto, p\u00e9s, dedos, curvinha das solas, almofadinhas dos p\u00e9s e muito mais, eram zonas er\u00f3genas t\u00e3o sexies quanto mamilos, seios, nuca, axilas, buceta&#8230; Ou onde mais viaje a imagina\u00e7\u00e3o, aliada ao tes\u00e3o.<\/p>\n\n\n\n<p>Ah, isso vale pro sexo mais &#8220;amorzinho&#8221; ao super hardcore (um &#8220;foot fucking&#8221; com o p\u00e9 em ponta&#8230; wow!) N\u00e3o se engane, viu?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">E se gostou deste texto, talvez goste desses tamb\u00e9m:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/xplastic.com.br\/podolatria-lesbica\/\" target=\"_blank\">Podolatria L\u00e9sbica &#8211; as mulheres que gostam dos p\u00e9s de outras mulheres<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/xplastic.com.br\/descobrindo-a-podolatria\/\" target=\"_blank\">Descobrindo a podolatria<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>E ent\u00e3o&#8230; N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes&#8230; O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a lesbopodolatria (ou podolatria feminina,&#8230;<\/p>\n","protected":false},"author":14,"featured_media":7334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","footnotes":""},"categories":[108],"tags":[72],"class_list":["post-3103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podolatria","tag-podolatria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira<\/title>\n<meta name=\"description\" content=\"&quot;N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira\" \/>\n<meta property=\"og:description\" content=\"&quot;N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\" \/>\n<meta property=\"og:site_name\" content=\"Xplastic Altporn\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-14T00:23:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T17:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/2016_BrancasComoLeite_Xplastic-139.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1864\" \/>\n\t<meta property=\"og:image:height\" content=\"1046\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beth Vieira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beth Vieira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\"},\"author\":{\"name\":\"Beth Vieira\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/1386f7cd5a47ec42104f94e504f416d4\"},\"headline\":\"Podolatria feminina e a Hist\u00f3ria de P.\",\"datePublished\":\"2020-02-14T00:23:00+00:00\",\"dateModified\":\"2020-02-26T17:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\"},\"wordCount\":535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"keywords\":[\"podolatria\"],\"articleSection\":[\"Podolatria\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\",\"name\":\"Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira\",\"isPartOf\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\"},\"datePublished\":\"2020-02-14T00:23:00+00:00\",\"dateModified\":\"2020-02-26T17:37:09+00:00\",\"description\":\"\\\"N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/xplastic.lv.localhost\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podolatria feminina e a Hist\u00f3ria de P.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#website\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"name\":\"Xplastic Altporn\",\"description\":\"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!\",\"publisher\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#organization\",\"name\":\"X-Plastic Altporn\",\"url\":\"https:\/\/xplastic.lv.localhost\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"X-Plastic Altporn\"},\"image\":{\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/1386f7cd5a47ec42104f94e504f416d4\",\"name\":\"Beth Vieira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/07a082c9e0fa605b5cc64c2b1d5dced4.jpg?ver=1777809156\",\"contentUrl\":\"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/07a082c9e0fa605b5cc64c2b1d5dced4.jpg?ver=1777809156\",\"caption\":\"Beth Vieira\"},\"description\":\"Beth Vieira \u00e9 carioca, designer de moda por forma\u00e7\u00e3o e escritora por paix\u00e3o. Desde 2003, vem internetando e desmistificando o sexo por a\u00ed..\",\"sameAs\":[\"https:\/\/bethpress.wordpress.com\"],\"url\":\"https:\/\/xplastic.com.br\/blog\/author\/beth-vieira\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira","description":"\"N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/","og_locale":"pt_BR","og_type":"article","og_title":"Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira","og_description":"\"N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.\"","og_url":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/","og_site_name":"Xplastic Altporn","article_published_time":"2020-02-14T00:23:00+00:00","article_modified_time":"2020-02-26T17:37:09+00:00","og_image":[{"width":1864,"height":1046,"url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2019\/05\/2016_BrancasComoLeite_Xplastic-139.jpg","type":"image\/jpeg"}],"author":"Beth Vieira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Beth Vieira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#article","isPartOf":{"@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/"},"author":{"name":"Beth Vieira","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/1386f7cd5a47ec42104f94e504f416d4"},"headline":"Podolatria feminina e a Hist\u00f3ria de P.","datePublished":"2020-02-14T00:23:00+00:00","dateModified":"2020-02-26T17:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/"},"wordCount":535,"commentCount":0,"publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"keywords":["podolatria"],"articleSection":["Podolatria"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/","url":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/","name":"Podolatria feminina e a Hist\u00f3ria de P. | Por Beth Vieira","isPartOf":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#website"},"datePublished":"2020-02-14T00:23:00+00:00","dateModified":"2020-02-26T17:37:09+00:00","description":"\"N\u00f3s, mulheres, gostamos de pezinhos tamb\u00e9m. \u00c9, rapazes... O erotismo que envolve o sexo entre mulheres, n\u00e3o descarta a podolatria feminina.\"","breadcrumb":{"@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xplastic.com.br\/blog\/podolatria-feminina-podolatria-lesbica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/xplastic.lv.localhost\/blog\/"},{"@type":"ListItem","position":2,"name":"Podolatria feminina e a Hist\u00f3ria de P."}]},{"@type":"WebSite","@id":"https:\/\/xplastic.lv.localhost\/blog\/#website","url":"https:\/\/xplastic.lv.localhost\/blog\/","name":"Xplastic Altporn","description":"Porn\u00f4 com hist\u00f3ria, mulheres tatuadas, altporn e muitas pervers\u00f5es!","publisher":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xplastic.lv.localhost\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/xplastic.lv.localhost\/blog\/#organization","name":"X-Plastic Altporn","url":"https:\/\/xplastic.lv.localhost\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/uploads\/2017\/07\/2017_TalitaporAlexandreMedeiros_Xplastic5.jpg","width":2048,"height":1365,"caption":"X-Plastic Altporn"},"image":{"@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/1386f7cd5a47ec42104f94e504f416d4","name":"Beth Vieira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/xplastic.lv.localhost\/blog\/#\/schema\/person\/image\/","url":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/07a082c9e0fa605b5cc64c2b1d5dced4.jpg?ver=1777809156","contentUrl":"https:\/\/xplastic.com.br\/blog\/wp-content\/litespeed\/avatar\/07a082c9e0fa605b5cc64c2b1d5dced4.jpg?ver=1777809156","caption":"Beth Vieira"},"description":"Beth Vieira \u00e9 carioca, designer de moda por forma\u00e7\u00e3o e escritora por paix\u00e3o. Desde 2003, vem internetando e desmistificando o sexo por a\u00ed..","sameAs":["https:\/\/bethpress.wordpress.com"],"url":"https:\/\/xplastic.com.br\/blog\/author\/beth-vieira\/"}]}},"_links":{"self":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/3103"}],"collection":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3103"}],"version-history":[{"count":0,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/posts\/3103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media\/7334"}],"wp:attachment":[{"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xplastic.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}